{"id":1364,"date":"2020-03-03T11:36:11","date_gmt":"2020-03-03T10:36:11","guid":{"rendered":"https:\/\/www.haus-des-erinnerns-mainz.de\/?p=1364"},"modified":"2020-03-03T11:36:11","modified_gmt":"2020-03-03T10:36:11","slug":"ausstellung-hier-bin-ich-selbstportraets-von-kindern-und-jugendlichen","status":"publish","type":"post","link":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/2020\/03\/03\/ausstellung-hier-bin-ich-selbstportraets-von-kindern-und-jugendlichen\/","title":{"rendered":"Ausstellung: \u201eHIER BIN ICH\u201c \u2013 Selbstportr\u00e4ts von Kindern und Jugendlichen"},"content":{"rendered":"\n<p>Ab dem 1. M\u00e4rz werden im Haus des Erinnerns \u2013 f\u00fcr Demokratie und Akzeptanz besondere Selbstportr\u00e4ts ausgestellt: Sie stammen von gefl\u00fcchteten Kindern und Jugendlichen, die in Mainz leben. Die K\u00fcnstlerin Susanna Storch bietet in Zusammenarbeit mit der Stiftung Juvente Mainz, seit vier Jahren in der Gemeinschaftsunterkunft Zwerchallee f\u00fcr junge Bewohner im Alter von 6 bis 17 Jahren die M\u00f6glichkeit, den Spa\u00df am kreativen Gestalten au\u00dferschulisch zu entdecken.<\/p>\n\n\n\n<p>Beim Erlernen unterschiedlicher Maltechniken konnten die Kinder und Jugendlichen sich mit ihrer Lebensgeschichte und ihrer Identit\u00e4t k\u00fcnstlerisch, selbstreflexiv und altersgerecht auseinandersetzen. So entstanden in diesem fortlaufenden Kreativkurs unter anderem Selbstportr\u00e4ts, die nun den Weg aus dem Kunstraum finden. Mit ihren Werken m\u00f6chten die Kinder und Jugendlichen der Erwachsenenwelt begegnen und auf bunte und anschauliche Weise zeigen, dass sie da sind \u2013 in Mainz angekommen sind. Die Selbstportr\u00e4ts warten schon auf ihren zugewiesenen Platz im privaten Wohnbereich, doch zuvor m\u00f6chten die jungen Akteur*innen die M\u00f6glichkeit nutzen, den interessierten Mainzer*innen ihre Werke und damit ein St\u00fcck weit sich selbst zu pr\u00e4sentieren. Dank der Kooperation zwischen dem Haus des Erinnerns \u2013 f\u00fcr Demokratie und Akzeptanz und der Fl\u00fcchtlingskoordination der Landeshauptstadt Mainz, konnte die Idee einer Ausstellung umgesetzt werden.<\/p>\n\n\n\n<p> Die Werke und Geschichten der jungen K\u00fcnstler*innen werden vom <strong>1. M\u00e4rz bis zum 10. M\u00e4rz 2020<\/strong> in den R\u00e4umlichkeiten des Haus des Erinnerns \u2013 f\u00fcr Demokratie und Akzeptanz in der Flachsmarktstra\u00dfe 36, 55116 Mainz ausgestellt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ab dem 1. M\u00e4rz werden im Haus des Erinnerns \u2013 f\u00fcr Demokratie und Akzeptanz besondere Selbstportr\u00e4ts ausgestellt: Sie stammen von gefl\u00fcchteten Kindern und Jugendlichen, die in Mainz leben. Die K\u00fcnstlerin Susanna Storch bietet in Zusammenarbeit mit der Stiftung Juvente Mainz, seit vier Jahren in der Gemeinschaftsunterkunft Zwerchallee f\u00fcr junge Bewohner&#8230;<\/p>\n<p> <a class=\"continue-reading-link\" href=\"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/2020\/03\/03\/ausstellung-hier-bin-ich-selbstportraets-von-kindern-und-jugendlichen\/\"><span>Weiterlesen<\/span><i class=\"crycon-right-dir\"><\/i><\/a> <\/p>\n","protected":false},"author":2,"featured_media":1347,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","ngg_post_thumbnail":0,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[75,1,86],"tags":[96,108,145,135,146],"series":[547],"class_list":["post-1364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-allgemein","category-archiv","tag-ausstellung","tag-flucht","tag-jugendliche","tag-kinder","tag-mainz","series-haus-des-erinnerns"],"episode_featured_image":"https:\/\/www.haus-des-erinnerns-mainz.de\/wp-content\/uploads\/2020\/02\/Selbstportraits-EinladungPNG.jpg","episode_player_image":"https:\/\/www.haus-des-erinnerns-mainz.de\/wp-content\/plugins\/seriously-simple-podcasting\/assets\/images\/no-album-art.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/www.haus-des-erinnerns-mainz.de\/feed\/podcast\/haus-des-erinnerns","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"9VAYOpiMIG\"><a href=\"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/2020\/03\/03\/ausstellung-hier-bin-ich-selbstportraets-von-kindern-und-jugendlichen\/\">Ausstellung: \u201eHIER BIN ICH\u201c \u2013 Selbstportr\u00e4ts von Kindern und Jugendlichen<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/2020\/03\/03\/ausstellung-hier-bin-ich-selbstportraets-von-kindern-und-jugendlichen\/embed\/#?secret=9VAYOpiMIG\" width=\"500\" height=\"350\" title=\"&#8222;Ausstellung: \u201eHIER BIN ICH\u201c \u2013 Selbstportr\u00e4ts von Kindern und Jugendlichen&#8220; &#8211; Haus des Erinnerns\" data-secret=\"9VAYOpiMIG\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/posts\/1364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/comments?post=1364"}],"version-history":[{"count":1,"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/posts\/1364\/revisions"}],"predecessor-version":[{"id":1365,"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/posts\/1364\/revisions\/1365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/media\/1347"}],"wp:attachment":[{"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/media?parent=1364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/categories?post=1364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/tags?post=1364"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/series?post=1364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}