{"id":1144,"date":"2019-10-08T18:09:05","date_gmt":"2019-10-08T16:09:05","guid":{"rendered":"https:\/\/www.haus-des-erinnerns-mainz.de\/?p=1144"},"modified":"2019-10-08T18:29:40","modified_gmt":"2019-10-08T16:29:40","slug":"kunstaktion-rettungsgasse","status":"publish","type":"post","link":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/2019\/10\/08\/kunstaktion-rettungsgasse\/","title":{"rendered":"Kunstaktion \u201eRettungsgasse\u201c"},"content":{"rendered":"\n<p>Von Cornelia Dold<\/p>\n\n\n\n<p>Am 24. September wurde am Mainzer Fischtorplatz die \u201eRettungsgasse\u201c von Ulrich A. Fay, Steinmetz und Steinbildhauermeister er\u00f6ffnet. Erm\u00f6glicht wurde die Aktion durch die Kulturabteilung der Stadt Mainz, insbesondere Frau Melanie Huber, der Projektleiterin Bildende Kunst sowie dem Haus des Erinnerns.<br><em>Was hat es mit den Rettungswesten auf sich, die seit Samstag hier zu sehen sind?<\/em><br>Der K\u00fcnstler will mit diesem Projekt aufmerksam machen, zur Diskussion anregen, die Themen Flucht, Menschenrechte und Engagement ins Bewusstsein der Zivilgesellschaft rufen. Ein ehemaliger Sockel eines Kriegerdenkmals aus dem deutsch-franz\u00f6sischen Krieg diente als Material. F\u00fcr die kommenden drei Wochen werden die daraus hergestellten Rettungswesten auf der Gr\u00fcnfl\u00e4che am Fischtorplatz zu sehen sein.<br>Der Name<em> \u201eRettungsgasse\u201c<\/em> soll dabei auf den oft sehr schmalen und gefahrvollen Korridor hinweisen, den Menschen auf dem Weg in Richtung ihrer Rettung eingehen.<\/p>\n\n\n\n<p>Dass der K\u00fcnstler Stein als Material f\u00fcr die Rettungswesten gew\u00e4hlt hat, steht symbolisch f\u00fcr die vermeintliche Sicherheit durch eine solche Weste. Denn obwohl Menschen auf ihrer Flucht Rettungswesten tragen, ertrinkt immer wieder ein Teil von ihnen auf ihrem Weg \u00fcber das Meer.<\/p>\n\n\n\n<p>Vielen Dank an Herrn Fay f\u00fcr seine k\u00fcnstlerische Arbeit und die Umsetzung der \u201eRettungsgasse\u201c, an Frau Melanie Huber f\u00fcr die Organisation und Erm\u00f6glichung des Projekts und an Herrn Carlos Wittmer, der sich als Integrationsbeauftragter der Stadt Mainz die Zeit nahm, bei der Er\u00f6ffnung einen Einblick in die aktuelle Situation Gefl\u00fcchteter in Mainz zu geben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Cornelia Dold Am 24. September wurde am Mainzer Fischtorplatz die \u201eRettungsgasse\u201c von Ulrich A. Fay, Steinmetz und Steinbildhauermeister er\u00f6ffnet. Erm\u00f6glicht wurde die Aktion durch die Kulturabteilung der Stadt Mainz, insbesondere Frau Melanie Huber, der Projektleiterin Bildende Kunst sowie dem Haus des Erinnerns.Was hat es mit den Rettungswesten auf sich,&#8230;<\/p>\n<p> <a class=\"continue-reading-link\" href=\"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/2019\/10\/08\/kunstaktion-rettungsgasse\/\"><span>Weiterlesen<\/span><i class=\"crycon-right-dir\"><\/i><\/a> <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","ngg_post_thumbnail":0,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[86,87],"tags":[96,97,98,99],"series":[547],"class_list":["post-1144","post","type-post","status-publish","format-standard","hentry","category-archiv","category-nachberichte","tag-ausstellung","tag-fluechtling","tag-kunstaktion","tag-rettungsgasse","series-haus-des-erinnerns"],"episode_featured_image":false,"episode_player_image":"https:\/\/www.haus-des-erinnerns-mainz.de\/wp-content\/plugins\/seriously-simple-podcasting\/assets\/images\/no-album-art.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/www.haus-des-erinnerns-mainz.de\/feed\/podcast\/haus-des-erinnerns","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"GDRZJuJfqS\"><a href=\"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/2019\/10\/08\/kunstaktion-rettungsgasse\/\">Kunstaktion \u201eRettungsgasse\u201c<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/2019\/10\/08\/kunstaktion-rettungsgasse\/embed\/#?secret=GDRZJuJfqS\" width=\"500\" height=\"350\" title=\"&#8222;Kunstaktion \u201eRettungsgasse\u201c&#8220; &#8211; Haus des Erinnerns\" data-secret=\"GDRZJuJfqS\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/posts\/1144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/comments?post=1144"}],"version-history":[{"count":3,"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/posts\/1144\/revisions"}],"predecessor-version":[{"id":1152,"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/posts\/1144\/revisions\/1152"}],"wp:attachment":[{"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/media?parent=1144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/categories?post=1144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/tags?post=1144"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/www.haus-des-erinnerns-mainz.de\/index.php\/wp-json\/wp\/v2\/series?post=1144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}